{"id":308,"date":"2025-07-03T09:40:11","date_gmt":"2025-07-03T09:40:11","guid":{"rendered":"https:\/\/www.villalecalvane.com\/?page_id=308"},"modified":"2025-09-18T13:17:15","modified_gmt":"2025-09-18T13:17:15","slug":"la-tenuta-in-esclusiva","status":"publish","type":"page","link":"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/","title":{"rendered":"La Tenuta in Esclusiva"},"content":{"rendered":"<p>A Le Calvane Luxury Estate l\u2019ospitalit\u00e0 raggiunge la sua massima espressione: un\u2019esperienza di esclusivit\u00e0 autentica, con l\u2019intero staff dedicato completamente a te, in ogni momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Le Calvane Luxury Estate l\u2019ospitalit\u00e0 raggiunge la sua massima espressione: un\u2019esperienza di esclusivit\u00e0 autentica, con l\u2019intero staff dedicato completamente a te, in ogni momento.<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":10,"comment_status":"closed","ping_status":"closed","template":"template-default-2.php","meta":{"footnotes":""},"categories":[],"class_list":["post-308","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Tenuta in Esclusiva &#8211; Villa Le Calvane<\/title>\n<meta name=\"description\" content=\"A Le Calvane Luxury Estate l\u2019ospitalit\u00e0 raggiunge la sua massima espressione: un\u2019esperienza di esclusivit\u00e0 autentica, con l\u2019intero staff dedicato completamente a te, in ogni momento..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Tenuta in Esclusiva &#8211; Villa Le Calvane\" \/>\n<meta property=\"og:description\" content=\"A Le Calvane Luxury Estate l\u2019ospitalit\u00e0 raggiunge la sua massima espressione: un\u2019esperienza di esclusivit\u00e0 autentica, con l\u2019intero staff dedicato completamente a te, in ogni momento..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/\" \/>\n<meta property=\"og:site_name\" content=\"Villa Le Calvane\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/VillaLeCalvane\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T13:17:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.villalecalvane.com\/wp-content\/uploads\/sites\/255\/2025\/06\/D9152-1024x683-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/la-tenuta-in-esclusiva\\\/\",\"url\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/la-tenuta-in-esclusiva\\\/\",\"name\":\"La Tenuta in Esclusiva &#8211; Villa Le Calvane\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/#website\"},\"datePublished\":\"2025-07-03T09:40:11+00:00\",\"dateModified\":\"2025-09-18T13:17:15+00:00\",\"description\":\"A Le Calvane Luxury Estate l\u2019ospitalit\u00e0 raggiunge la sua massima espressione: un\u2019esperienza di esclusivit\u00e0 autentica, con l\u2019intero staff dedicato completamente a te, in ogni momento..\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/la-tenuta-in-esclusiva\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/la-tenuta-in-esclusiva\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/la-tenuta-in-esclusiva\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Tenuta in Esclusiva\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/\",\"name\":\"Villa Le Calvane\",\"description\":\"Villa le Calvane  a Montespertoli, Chianti, Firenze - Prenotazione di un hotel  nel cuore del Chianti\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/#organization\"},\"alternateName\":\"Villa Le Calvane\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/#organization\",\"name\":\"Villa Le Calvane\",\"alternateName\":\"Villa Le Calvane\",\"url\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/villa-le-calvane.ms2.decms.eu\\\/wp-content\\\/uploads\\\/sites\\\/255\\\/2025\\\/06\\\/lecalvane_logo_blue_2.png\",\"contentUrl\":\"https:\\\/\\\/villa-le-calvane.ms2.decms.eu\\\/wp-content\\\/uploads\\\/sites\\\/255\\\/2025\\\/06\\\/lecalvane_logo_blue_2.png\",\"width\":200,\"height\":87,\"caption\":\"Villa Le Calvane\"},\"image\":{\"@id\":\"https:\\\/\\\/www.villalecalvane.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/VillaLeCalvane\\\/\",\"https:\\\/\\\/www.instagram.com\\\/lecalvane\\\/\",\"https:\\\/\\\/www.tripadvisor.ca\\\/Hotel_Review-g644278-d12294738-Reviews-Villa_Le_Calvane-Montespertoli_Tuscany.html\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Tenuta in Esclusiva &#8211; Villa Le Calvane","description":"A Le Calvane Luxury Estate l\u2019ospitalit\u00e0 raggiunge la sua massima espressione: un\u2019esperienza di esclusivit\u00e0 autentica, con l\u2019intero staff dedicato completamente a te, in ogni momento..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/","og_locale":"it_IT","og_type":"article","og_title":"La Tenuta in Esclusiva &#8211; Villa Le Calvane","og_description":"A Le Calvane Luxury Estate l\u2019ospitalit\u00e0 raggiunge la sua massima espressione: un\u2019esperienza di esclusivit\u00e0 autentica, con l\u2019intero staff dedicato completamente a te, in ogni momento..","og_url":"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/","og_site_name":"Villa Le Calvane","article_publisher":"https:\/\/www.facebook.com\/VillaLeCalvane\/","article_modified_time":"2025-09-18T13:17:15+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/www.villalecalvane.com\/wp-content\/uploads\/sites\/255\/2025\/06\/D9152-1024x683-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/","url":"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/","name":"La Tenuta in Esclusiva &#8211; Villa Le Calvane","isPartOf":{"@id":"https:\/\/www.villalecalvane.com\/it\/#website"},"datePublished":"2025-07-03T09:40:11+00:00","dateModified":"2025-09-18T13:17:15+00:00","description":"A Le Calvane Luxury Estate l\u2019ospitalit\u00e0 raggiunge la sua massima espressione: un\u2019esperienza di esclusivit\u00e0 autentica, con l\u2019intero staff dedicato completamente a te, in ogni momento..","breadcrumb":{"@id":"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.villalecalvane.com\/it\/la-tenuta-in-esclusiva\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.villalecalvane.com\/it\/"},{"@type":"ListItem","position":2,"name":"La Tenuta in Esclusiva"}]},{"@type":"WebSite","@id":"https:\/\/www.villalecalvane.com\/it\/#website","url":"https:\/\/www.villalecalvane.com\/it\/","name":"Villa Le Calvane","description":"Villa le Calvane  a Montespertoli, Chianti, Firenze - Prenotazione di un hotel  nel cuore del Chianti","publisher":{"@id":"https:\/\/www.villalecalvane.com\/it\/#organization"},"alternateName":"Villa Le Calvane","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.villalecalvane.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.villalecalvane.com\/it\/#organization","name":"Villa Le Calvane","alternateName":"Villa Le Calvane","url":"https:\/\/www.villalecalvane.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.villalecalvane.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/villa-le-calvane.ms2.decms.eu\/wp-content\/uploads\/sites\/255\/2025\/06\/lecalvane_logo_blue_2.png","contentUrl":"https:\/\/villa-le-calvane.ms2.decms.eu\/wp-content\/uploads\/sites\/255\/2025\/06\/lecalvane_logo_blue_2.png","width":200,"height":87,"caption":"Villa Le Calvane"},"image":{"@id":"https:\/\/www.villalecalvane.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/VillaLeCalvane\/","https:\/\/www.instagram.com\/lecalvane\/","https:\/\/www.tripadvisor.ca\/Hotel_Review-g644278-d12294738-Reviews-Villa_Le_Calvane-Montespertoli_Tuscany.html"]}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/www.villalecalvane.com\/it\/wp-json\/wp\/v2\/pages\/308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.villalecalvane.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.villalecalvane.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.villalecalvane.com\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.villalecalvane.com\/it\/wp-json\/wp\/v2\/comments?post=308"}],"version-history":[{"count":0,"href":"https:\/\/www.villalecalvane.com\/it\/wp-json\/wp\/v2\/pages\/308\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.villalecalvane.com\/it\/wp-json\/wp\/v2\/media?parent=308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.villalecalvane.com\/it\/wp-json\/wp\/v2\/categories?post=308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}